{"id":8416,"date":"2014-03-09T16:24:40","date_gmt":"2014-03-09T19:24:40","guid":{"rendered":"http:\/\/treetech.com.br\/articulos\/otros\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico"},"modified":"2023-12-04T18:00:03","modified_gmt":"2023-12-04T21:00:03","slug":"la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico","status":"publish","type":"post","link":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/","title":{"rendered":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]Cada tres a\u00f1os la planta industrial de Polietileno de Braskem en Cubat\u00e3o interrumpe sus actividades para inspecci\u00f3n y mantenimiento general de sus instalaciones. Son inspeccionadas m\u00e1quinas y estructuras, adem\u00e1s de las condiciones del sistema el\u00e9ctrico que recibe atenci\u00f3n especial con actividades espec\u00edficas, principalmente en la subestaci\u00f3n de energ\u00eda.<\/p>\n<p>Debido a que la energ\u00eda el\u00e9ctrica es un insumo fundamental para la producci\u00f3n industrial, es necesario que todos los activos de la subestaci\u00f3n est\u00e9n en perfecto estado de funcionamiento. Por lo tanto, cada detalle del sistema es verificado, como los equipos de maniobra (disyuntores y seccionadores), los aisladores (TCs y TPs) y, en destaque, el transformador de energ\u00eda.<\/p>\n<p>La subestaci\u00f3n de la planta de Cubat\u00e3o posee apenas un transformador, de 88 kV \/ 13,8 kV de 20 MVA, que no puede presentar ninguna inconsistencia, ya que puede representar grandes perjuicios a la empresa. La unidad produce Polietileno de Baja Densidad (PEBD) y su producci\u00f3n alcanza 140 toneladas anuales de material.<\/p>\n<p>La acci\u00f3n del equipo t\u00e9cnica y de mantenimiento de la empresa busca mantener la seguridad de los colaboradores, alcanzar el mayor desempe\u00f1o de los activos adem\u00e1s de obtener el suministro ininterrumpido de electricidad para atender al constante crecimiento productivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-482\" src=\"http:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/RGL_7643.jpg\" alt=\"RGL_7643\" width=\"550\" height=\"366\" srcset=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/RGL_7643.jpg 800w, https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/RGL_7643-300x199.jpg 300w, https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/RGL_7643-272x182.jpg 272w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<h2>Modernizaci\u00f3n del sistema de la unidad de Cubat\u00e3o de Braskem<\/h2>\n<p>En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo <em>online<\/em> para la gesti\u00f3n completa del equipo.<\/p>\n<p>Por iniciativa del Ingeniero de Fiabilidad, Jo\u00e3o Luiz G. Neto, interesado en garantizar el suministro el\u00e9ctrico a la planta, se busc\u00f3 una soluci\u00f3n con la finalidad de mejorar la calidad del propio sistema (con el aumento de la fiabilidad de operaci\u00f3n del activo) y tornar el trabajo de mantenimiento m\u00e1s asertivo e inteligente.<\/p>\n<p>El proyecto consisti\u00f3 en el uso de un conjunto de IEDs (sensores inteligentes) para el monitoreo de las variables del transformador, con soporte del <em>software<\/em> especialista Sigma para diagn\u00f3sticos y pron\u00f3sticos en tiempo real. Con estas herramientas, el equipo de mantenimiento obtiene informaciones confiables para ayudar en la toma de decisiones.<\/p>\n<p>El sistema planificado contempla el monitoreo completo de los bujes capacitivos, retirada y sustituci\u00f3n de los term\u00f3metros anal\u00f3gicos antiguos por el monitor de temperatura digital, regulaci\u00f3n de tensi\u00f3n autom\u00e1tica y monitoreo del conmutador sobre carga, adem\u00e1s del seguimiento <em>online<\/em> del gas (H2) y humedad disueltos en el aceite aislante.<\/p>\n<figure id=\"attachment_480\" aria-describedby=\"caption-attachment-480\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-480 size-full\" src=\"http:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg\" alt=\"\" width=\"600\" height=\"450\" \/><figcaption id=\"caption-attachment-480\" class=\"wp-caption-text\">SE de la planta de Polietileno de Braskem de Cubat\u00e3o<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-6675\" src=\"http:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/lg-sigma4net-azul-300x273.png\" alt=\"lg-sigma4net-azul\" width=\"300\" height=\"273\" srcset=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/lg-sigma4net-azul-300x273.png 300w, https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/lg-sigma4net-azul.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Estos equipos est\u00e1n interconectados y env\u00edan informaciones (mediciones) a un Data Center localizado en la sala de mando de la subestaci\u00f3n. Estas informaciones ser\u00e1n accedidas por el equipo Braskem remotamente, por medio del <em>software<\/em> de monitoreo y gesti\u00f3n de activo <a href=\"https:\/\/treetech.com.br\/es\/sigma-ecm\" target=\"_blank\" rel=\"noopener\">Sigma4net<\/a>&#x2122; (disponible para las computadoras interconectados en la red corporativa de la empresa).<\/p>\n<blockquote>\n<p>\u201cPodemos localizar todas las mediciones realizadas en el transformador principal de la computadora, adem\u00e1s de visualizar de forma r\u00e1pida los diagn\u00f3sticos y pron\u00f3sticos ofrecidos por el <em>software<\/em>. El sistema tambi\u00e9n nos ayuda en el mejor mantenimiento de la m\u00e1quina, en las consultas r\u00e1pidas a los gr\u00e1ficos y en las tendencias en torno de la operaci\u00f3n de ellas\u201d, afirma el Ing. Jo\u00e3o Luiz Gon\u00e7alves Neto, responsable por la implementaci\u00f3n y operaci\u00f3n del nuevo sistema.<\/p>\n<\/blockquote>\n<p>A partir de ahora, todo el equipo de mantenimiento tendr\u00e1 la disposici\u00f3n a las mismas informaciones, de esta forma, conseguir\u00e1 localizar el desempe\u00f1o del transformador y as\u00ed, elaborar planes eficientes para su mantenimiento. Mientras que durante la instalaci\u00f3n hubo una gran interacci\u00f3n con el nuevo sistema, como lo se\u00f1ala el propio Jo\u00e3o, \u201cel equipo Treetech nos ha apoyado con todas las informaciones que necesitamos para aprovechar la m\u00e1xima eficiencia del sistema. Nuestra experiencia aunada al soporte Treetech nos pondr\u00e1 a la vanguardia del mantenimiento predictivo en subestaciones de energ\u00eda\u201d.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-485 alignleft\" src=\"http:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/sensores-254x300.jpg\" alt=\"sensores\" width=\"249\" height=\"294\" srcset=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/sensores-254x300.jpg 254w, https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/sensores.jpg 450w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/p>\n<blockquote>\n<p>\u201cPor tratarse de un equipo fundamental para la continuidad de la producci\u00f3n aqu\u00ed en Braskem, fue muy importante la instalaci\u00f3n del sistema de monitoreo, lo que demuestra la preocupaci\u00f3n y el cuidado con el equipo. Todo el equipo est\u00e1 consciente de que la nueva herramienta ayudar\u00e1 tanto para acciones de mantenimiento, como para determinar nuevas inversiones, basadas en el estado de funcionamiento de este transformador\u201d, menciona Jos\u00e9 Moitinho, ingeniero de aplicaciones de Treetech.<\/p>\n<\/blockquote>\n<p>Las ventajas no se limitan s\u00f3lo en proveer acciones correctivas o preventivas para mantener el funcionamiento del transformador; con la ayuda del sistema de monitoreo, los equipos de mantenimiento y operaci\u00f3n podr\u00e1n indicar el \u00e1rea financiera y de planificaci\u00f3n cuando ser\u00e1 necesaria la sustituci\u00f3n o adquisici\u00f3n de nuevos equipos para suplir la creciente demanda de la planta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-483 alignright\" src=\"http:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/RGL_7668.jpg\" alt=\"RGL_7668\" width=\"250\" height=\"380\" \/><br \/>\n<strong>Con el uso del Sigma, la unidad de Braskem en Cubat\u00e3o podr\u00e1 realizar:<\/strong><\/p>\n<ul>\n<li>Diagn\u00f3stico <em>online<\/em> del estado del transformador;<\/li>\n<li>Visualizaci\u00f3n de alarmas y alertas y actuar seg\u00fan las normas y procedimiento aplicables a las condiciones de operaci\u00f3n normal y de contingencias;<\/li>\n<li>Acciones de mantenimiento, operaci\u00f3n y planificaci\u00f3n;<\/li>\n<li>Estandarizaci\u00f3n de las acciones y de la comunicaci\u00f3n en el \u00e1rea de mantenimiento;<\/li>\n<li>Identificaci\u00f3n de oportunidades de optimizaci\u00f3n de la eficiencia de los activos;<\/li>\n<li>Gesti\u00f3n efectiva da mantenimiento por medio de informes peri\u00f3dicos de desempe\u00f1o y del estado de los activos;<\/li>\n<\/ul>\n<p><strong>A continuaci\u00f3n, la relaci\u00f3n de los equipos y soluciones que integran el transformador TR1 (20 MVA) de 88 kV de la SE Braskem en Cubat\u00e3o:<\/strong><\/p>\n<ol>\n<li>TM1 \u2013 Monitor de Temperatura<\/li>\n<li>BM (Monitor de Bujes) para AT<\/li>\n<li>AVR \u2013 Rel\u00e9 Regulador de Tensi\u00f3n<\/li>\n<li>IDM \u2013 Monitor de la Torsi\u00f3n del Conmutador<\/li>\n<li>GMP \u2013 Monitor de Gas y humedad<\/li>\n<li><em>Software<\/em> Sigma4net&#x2122;<\/li>\n<li>Capacitaci\u00f3n completa de uso y funcionamiento del sistema.<\/li>\n<\/ol>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Cada tres a\u00f1os la planta industrial de Polietileno de Braskem en Cubat\u00e3o interrumpe sus actividades para inspecci\u00f3n y mantenimiento general de sus instalaciones. Son inspeccionadas m\u00e1quinas y estructuras, adem\u00e1s de las condiciones del sistema el\u00e9ctrico que recibe atenci\u00f3n especial con actividades espec\u00edficas, principalmente en la subestaci\u00f3n de energ\u00eda. Debido a que la energ\u00eda el\u00e9ctrica es&hellip;<\/p>\n","protected":false},"author":1,"featured_media":480,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[131],"tags":[],"class_list":["post-8416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casos","entry","has-media"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fernando FCA\"\/>\n\t<meta name=\"google-site-verification\" content=\"1gr4jSvU9APDpv5zz03wvWHDR5GrF-XaMgV7wqMEM3E\" \/>\n\t<meta name=\"keywords\" content=\"treetech,braskem,cubat\u00e3o,monitoreo,ieds,software,sigma,casos\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Treetech | Smart solutions for smart grids\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech\" \/>\n\t\t<meta property=\"og:description\" content=\"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-03-09T19:24:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-04T21:00:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#article\",\"name\":\"La unidad de Braskem en Cubat\\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\\u00e9ctrico | Treetech\",\"headline\":\"La unidad de Braskem en Cubat\\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\\u00e9ctrico\",\"author\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/author\\\/angulo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSCF11572-e1454013934583.jpg\",\"width\":600,\"height\":450,\"caption\":\"SE da planta de Polietileno da Braskem de Cubat\\u00e3o\"},\"datePublished\":\"2014-03-09T16:24:40-03:00\",\"dateModified\":\"2023-12-04T18:00:03-03:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#webpage\"},\"articleSection\":\"Casos, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/category\\\/casos\\\/#listItem\",\"name\":\"Casos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/category\\\/casos\\\/#listItem\",\"position\":2,\"name\":\"Casos\",\"item\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/category\\\/casos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#listItem\",\"name\":\"La unidad de Braskem en Cubat\\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\\u00e9ctrico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#listItem\",\"position\":3,\"name\":\"La unidad de Braskem en Cubat\\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\\u00e9ctrico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/category\\\/casos\\\/#listItem\",\"name\":\"Casos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#organization\",\"name\":\"Treetech Tecnologia\",\"description\":\"Smart solutions for smart grids\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/\",\"telephone\":\"+5511987750708\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/lg-treetech-retina.png\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#organizationLogo\",\"width\":180,\"height\":180,\"caption\":\"lg-treetech-retina\"},\"image\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt2C9e4WvpLPJOGR5Rxt6YQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/treetech-sistemas-digitais\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/author\\\/angulo\\\/#author\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/author\\\/angulo\\\/\",\"name\":\"Fernando FCA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#webpage\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/\",\"name\":\"La unidad de Braskem en Cubat\\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\\u00e9ctrico | Treetech\",\"description\":\"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\\u00f3 la modernizaci\\u00f3n del sistema de protecci\\u00f3n t\\u00e9rmica de un transformador e implement\\u00f3 el sistema de monitoreo en l\\u00ednea para la gesti\\u00f3n completa del equipo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/author\\\/angulo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/author\\\/angulo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/DSCF11572-e1454013934583.jpg\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#mainImage\",\"width\":600,\"height\":450,\"caption\":\"SE da planta de Polietileno da Braskem de Cubat\\u00e3o\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\\\/#mainImage\"},\"datePublished\":\"2014-03-09T16:24:40-03:00\",\"dateModified\":\"2023-12-04T18:00:03-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/\",\"name\":\"Treetech\",\"description\":\"Smart solutions for smart grids\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/treetech.com.br\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech","description":"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.","canonical_url":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/","robots":"max-image-preview:large","keywords":"treetech,braskem,cubat\u00e3o,monitoreo,ieds,software,sigma,casos","webmasterTools":{"google-site-verification":"1gr4jSvU9APDpv5zz03wvWHDR5GrF-XaMgV7wqMEM3E","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#article","name":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech","headline":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico","author":{"@id":"https:\/\/treetech.com.br\/es\/author\/angulo\/#author"},"publisher":{"@id":"https:\/\/treetech.com.br\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg","width":600,"height":450,"caption":"SE da planta de Polietileno da Braskem de Cubat\u00e3o"},"datePublished":"2014-03-09T16:24:40-03:00","dateModified":"2023-12-04T18:00:03-03:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#webpage"},"isPartOf":{"@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#webpage"},"articleSection":"Casos, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/treetech.com.br\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/category\/casos\/#listItem","name":"Casos"}},{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/category\/casos\/#listItem","position":2,"name":"Casos","item":"https:\/\/treetech.com.br\/es\/category\/casos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#listItem","name":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#listItem","position":3,"name":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico","previousItem":{"@type":"ListItem","@id":"https:\/\/treetech.com.br\/es\/category\/casos\/#listItem","name":"Casos"}}]},{"@type":"Organization","@id":"https:\/\/treetech.com.br\/es\/#organization","name":"Treetech Tecnologia","description":"Smart solutions for smart grids","url":"https:\/\/treetech.com.br\/es\/","telephone":"+5511987750708","logo":{"@type":"ImageObject","url":"https:\/\/treetech.com.br\/wp-content\/uploads\/2016\/03\/lg-treetech-retina.png","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#organizationLogo","width":180,"height":180,"caption":"lg-treetech-retina"},"image":{"@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCt2C9e4WvpLPJOGR5Rxt6YQ","https:\/\/www.linkedin.com\/company\/treetech-sistemas-digitais"]},{"@type":"Person","@id":"https:\/\/treetech.com.br\/es\/author\/angulo\/#author","url":"https:\/\/treetech.com.br\/es\/author\/angulo\/","name":"Fernando FCA"},{"@type":"WebPage","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#webpage","url":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/","name":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech","description":"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/treetech.com.br\/es\/#website"},"breadcrumb":{"@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#breadcrumblist"},"author":{"@id":"https:\/\/treetech.com.br\/es\/author\/angulo\/#author"},"creator":{"@id":"https:\/\/treetech.com.br\/es\/author\/angulo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg","@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#mainImage","width":600,"height":450,"caption":"SE da planta de Polietileno da Braskem de Cubat\u00e3o"},"primaryImageOfPage":{"@id":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/#mainImage"},"datePublished":"2014-03-09T16:24:40-03:00","dateModified":"2023-12-04T18:00:03-03:00"},{"@type":"WebSite","@id":"https:\/\/treetech.com.br\/es\/#website","url":"https:\/\/treetech.com.br\/es\/","name":"Treetech","description":"Smart solutions for smart grids","inLanguage":"es-ES","publisher":{"@id":"https:\/\/treetech.com.br\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Treetech | Smart solutions for smart grids","og:type":"article","og:title":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech","og:description":"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.","og:url":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/","og:image":"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg","og:image:secure_url":"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg","og:image:width":600,"og:image:height":450,"article:published_time":"2014-03-09T19:24:40+00:00","article:modified_time":"2023-12-04T21:00:03+00:00","twitter:card":"summary","twitter:title":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | Treetech","twitter:description":"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.","twitter:image":"https:\/\/treetech.com.br\/wp-content\/uploads\/2014\/03\/DSCF11572-e1454013934583.jpg"},"aioseo_meta_data":{"post_id":"8416","title":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico | #site_title","description":"En marzo de 2011, durante la parada de la planta para los procesos de mantenimiento, la unidad de Braskem de Cubat\u00e3o, en alianza con Treetech Sistemas Digitais, realiz\u00f3 la modernizaci\u00f3n del sistema de protecci\u00f3n t\u00e9rmica de un transformador e implement\u00f3 el sistema de monitoreo en l\u00ednea para la gesti\u00f3n completa del equipo.","keywords":[{"label":"Treetech","value":"Treetech"},{"label":"Braskem","value":"Braskem"},{"label":"Cubat\u00e3o","value":"Cubat\u00e3o"},{"label":"Monitoreo","value":"Monitoreo"},{"label":"IEDs","value":"IEDs"},{"label":"Software","value":"Software"},{"label":"Sigma","value":"Sigma"},{"label":"Casos","value":"Casos"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-24 05:36:11","updated":"2025-06-04 23:38:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/treetech.com.br\/es\/\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/treetech.com.br\/es\/category\/casos\/\" title=\"Casos\">Casos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/treetech.com.br\/es\/"},{"label":"Casos","link":"https:\/\/treetech.com.br\/es\/category\/casos\/"},{"label":"La unidad de Braskem en Cubat\u00e3o realiza mantenimiento completo en su planta y aumenta la fiabilidad de su sistema el\u00e9ctrico","link":"https:\/\/treetech.com.br\/es\/la-unidad-de-braskem-en-cubatao-realiza-mantenimiento-completo-en-su-planta-y-aumenta-la-fiabilidad-de-su-sistema-electrico\/"}],"_links":{"self":[{"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/posts\/8416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/comments?post=8416"}],"version-history":[{"count":0,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/posts\/8416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/media\/480"}],"wp:attachment":[{"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/media?parent=8416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/categories?post=8416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/treetech.com.br\/es\/wp-json\/wp\/v2\/tags?post=8416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}